{"id":82,"date":"2011-11-01T11:41:24","date_gmt":"2011-11-01T10:41:24","guid":{"rendered":"http:\/\/deutsch-fuer-juristen.de\/?page_id=82"},"modified":"2021-05-06T21:11:49","modified_gmt":"2021-05-06T19:11:49","slug":"teaching-materials","status":"publish","type":"page","link":"https:\/\/deutsch-fuer-juristen.de\/en\/german-courses\/teaching-materials\/","title":{"rendered":"Teaching Materials"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li>Audiovisual aids as films, newspaper articles, radio programmes with particular legal reference.<\/li>\n<\/ul>\n<ul>\n<li>Legal texts such as German regulations, judgements, legal commentaries and legal magazines.<\/li>\n<\/ul>\n<ul>\n<li>General German as a Foreign Language material applied with specific legal reference.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Audiovisual aids as films, newspaper articles, radio programmes with particular legal reference. Legal texts such as German regulations, judgements, legal commentaries and legal magazines. General German as a Foreign Language material applied with specific legal reference.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":76,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"content-sidebar"},"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/pages\/82"}],"collection":[{"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":2,"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/pages\/82\/revisions"}],"predecessor-version":[{"id":1256,"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/pages\/82\/revisions\/1256"}],"up":[{"embeddable":true,"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/pages\/76"}],"wp:attachment":[{"href":"https:\/\/deutsch-fuer-juristen.de\/en\/wp-json\/wp\/v2\/media?parent=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}